{"id":6834,"date":"2026-02-06T02:25:53","date_gmt":"2026-02-05T18:25:53","guid":{"rendered":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/"},"modified":"2026-02-06T02:25:53","modified_gmt":"2026-02-05T18:25:53","slug":"understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects","status":"publish","type":"post","link":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/","title":{"rendered":"ArchiMate\u3068TOGAF\u306e\u9055\u3044\u3092\u7406\u89e3\u3059\u308b\uff1a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u306e\u305f\u3081\u306e\u30ac\u30a4\u30c9"},"content":{"rendered":"<p>\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u3068\u3057\u3066\u3001ArchiMate\u3068TOGAF\u306f\u3001\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u305f\u3081\u306e\u6700\u3082\u5e83\u304f\u4f7f\u7528\u3055\u308c\u3066\u3044\u308b\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u306e2\u3064\u3067\u3042\u308b\u53ef\u80fd\u6027\u304c\u9ad8\u3044\u3067\u3059\u3002ArchiMate\u3068TOGAF\u306e\u4e21\u65b9\u306b\u306f\u591a\u304f\u306e\u985e\u4f3c\u70b9\u304c\u3042\u308a\u307e\u3059\u304c\u3001\u91cd\u8981\u306a\u9055\u3044\u3082\u3042\u308a\u307e\u3059\u3002\u3053\u306e\u8a18\u4e8b\u3067\u306f\u3001\u3053\u308c\u3089\u306e\u9055\u3044\u3092\u691c\u8a0e\u3059\u308b\u3053\u3068\u3067\u3001\u3042\u306a\u305f\u306e\u30cb\u30fc\u30ba\u306b\u5408\u3063\u305f\u9069\u5207\u306a\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u3092\u9078\u629e\u3059\u308b\u624b\u52a9\u3051\u3092\u3057\u307e\u3059\u3002<\/p>\n<p><!--more--><\/p>\n<h2>ArchiMate\u3068\u306f\u4f55\u304b<\/h2>\n<p>ArchiMate\u306f\u3001\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u8981\u7d20\u9593\u306e\u95a2\u4fc2\u3092\u8a18\u8ff0\u3001\u5206\u6790\u3001\u53ef\u8996\u5316\u3059\u308b\u305f\u3081\u306e\u5171\u901a\u306e\u8a00\u8a9e\u3068\u30d5\u30ec\u30fc\u30e0\u30ef\u30fc\u30af\u3092\u63d0\u4f9b\u3059\u308b\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u3067\u3059\u3002ArchiMate\u306f\u30aa\u30fc\u30d7\u30f3\u3067\u975e\u7279\u8a31\u7684\u306a\u8a00\u8a9e\u3067\u3042\u308a\u3001\u4e16\u754c\u4e2d\u306e\u7d44\u7e54\u306b\u3088\u3063\u3066\u5e83\u304f\u63a1\u7528\u3055\u308c\u3066\u3044\u307e\u3059\u3002<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/guides.visual-paradigm.com\/wp-content\/uploads\/2023\/02\/1_archimate-diagram-example.png\"\/><\/p>\n<h2>TOGAF\u3068\u306f\u4f55\u304b\uff1f<\/h2>\n<p>TOGAF\u306f\u3001\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u958b\u767a\u3068\u7ba1\u7406\u306b\u5305\u62ec\u7684\u306a\u30a2\u30d7\u30ed\u30fc\u30c1\u3092\u63d0\u4f9b\u3059\u308b\u30d5\u30ec\u30fc\u30e0\u30ef\u30fc\u30af\u3067\u3059\u3002TOGAF\u306b\u306f\u3001\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u305f\u3081\u306e\u30d9\u30b9\u30c8\u30d7\u30e9\u30af\u30c6\u30a3\u30b9\u3001\u624b\u6cd5\u3001\u30c4\u30fc\u30eb\u306e\u30bb\u30c3\u30c8\u306b\u52a0\u3048\u3066\u3001\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u3092\u8a18\u8ff0\u3059\u308b\u305f\u3081\u306e\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u3082\u542b\u307e\u308c\u3066\u3044\u307e\u3059\u3002TOGAF\u306f\u3001\u30b0\u30ed\u30fc\u30d0\u30eb\u306a\u7d44\u7e54\u9023\u5408\u3067\u3042\u308bThe Open Group\u306b\u3088\u3063\u3066\u6240\u6709\u304a\u3088\u3073\u7dad\u6301\u3055\u308c\u3066\u3044\u307e\u3059\u3002<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/guides.visual-paradigm.com\/wp-content\/uploads\/2023\/02\/04-togaf-steps-and-deliverables.png\"\/><\/p>\n<h2>ArchiMate\u3068TOGAF\u306e\u4e3b\u306a\u9055\u3044<\/h2>\n<ul>\n<li><strong>\u7126\u70b9<\/strong>\uff1aArchiMate\u306f\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u30e2\u30c7\u30eb\u5316\u306b\u7279\u5316\u3057\u3066\u3044\u308b\u306e\u306b\u5bfe\u3057\u3001TOGAF\u306f\u30d9\u30b9\u30c8\u30d7\u30e9\u30af\u30c6\u30a3\u30b9\u3001\u624b\u6cd5\u3001\u30c4\u30fc\u30eb\u3092\u542b\u3080\u3001\u3088\u308a\u5305\u62ec\u7684\u306a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u30a2\u30d7\u30ed\u30fc\u30c1\u3092\u63d0\u4f9b\u3057\u3066\u3044\u307e\u3059\u3002<\/li>\n<li><strong>\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e<\/strong>\uff1aArchiMate\u306f\u72ec\u7acb\u3057\u305f\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u3067\u3042\u308b\u306e\u306b\u5bfe\u3057\u3001TOGAF\u306e\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u306f\u3001\u3088\u308a\u5927\u304d\u306aTOGAF\u30d5\u30ec\u30fc\u30e0\u30ef\u30fc\u30af\u306e\u4e00\u90e8\u306b\u3059\u304e\u307e\u305b\u3093\u3002<\/li>\n<li><strong>\u958b\u653e\u6027<\/strong>\uff1aArchiMate\u306f\u30aa\u30fc\u30d7\u30f3\u3067\u975e\u7279\u8a31\u7684\u306a\u8a00\u8a9e\u3067\u3042\u308b\u306e\u306b\u5bfe\u3057\u3001TOGAF\u306fThe Open Group\u306b\u3088\u3063\u3066\u6240\u6709\u304a\u3088\u3073\u7dad\u6301\u3055\u308c\u3066\u3044\u307e\u3059\u3002<\/li>\n<li><strong>\u63a1\u7528\u72b6\u6cc1<\/strong>\uff1aArchiMate\u306f\u4e16\u754c\u4e2d\u306e\u7d44\u7e54\u306b\u3088\u3063\u3066\u5e83\u304f\u63a1\u7528\u3055\u308c\u3066\u3044\u307e\u3059\u304c\u3001TOGAF\u306f\u4e3b\u306b\u8907\u96d1\u306a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u30cb\u30fc\u30ba\u3092\u6301\u3064\u5927\u898f\u6a21\u306a\u7d44\u7e54\u3067\u4f7f\u7528\u3055\u308c\u3066\u3044\u307e\u3059\u3002<\/li>\n<\/ul>\n<h2>\u3042\u306a\u305f\u306e\u30cb\u30fc\u30ba\u306b\u5408\u3063\u305f\u9069\u5207\u306a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30c4\u30fc\u30eb\u3092\u9078\u3076<\/h2>\n<p>ArchiMate\u3068TOGAF\u306e\u3069\u3061\u3089\u3092\u9078\u3076\u304b\u3092\u691c\u8a0e\u3059\u308b\u969b\u306e\u91cd\u8981\u306a\u8981\u56e0\u306f\u3001\u3042\u306a\u305f\u306e\u7279\u5b9a\u306e\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u30cb\u30fc\u30ba\u3067\u3059\u3002\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u7528\u306b\u30b7\u30f3\u30d7\u30eb\u3067\u67d4\u8edf\u6027\u304c\u3042\u308a\u3001\u5e83\u304f\u63a1\u7528\u3055\u308c\u3066\u3044\u308b\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u304c\u5fc5\u8981\u306a\u5834\u5408\u3001ArchiMate\u304c\u3088\u308a\u9069\u3057\u305f\u9078\u629e\u3068\u306a\u308b\u3067\u3057\u3087\u3046\u3002\u4e00\u65b9\u3001\u30d9\u30b9\u30c8\u30d7\u30e9\u30af\u30c6\u30a3\u30b9\u3001\u624b\u6cd5\u3001\u30c4\u30fc\u30eb\u3092\u542b\u3080\u5305\u62ec\u7684\u306a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u30a2\u30d7\u30ed\u30fc\u30c1\u304c\u5fc5\u8981\u306a\u5834\u5408\u3001TOGAF\u304c\u3088\u308a\u9069\u3057\u305f\u9078\u629e\u3068\u306a\u308a\u307e\u3059\u3002<\/p>\n<h2>Visual Paradigm\uff1aArchiMate\u304a\u3088\u3073TOGAF\u30e2\u30c7\u30eb\u5316\u306e\u7a76\u6975\u306e\u30bd\u30ea\u30e5\u30fc\u30b7\u30e7\u30f3<\/h2>\n<p>Visual Paradigm\u306f\u3001ArchiMate\u3068TOGAF\u306e\u4e21\u65b9\u3092\u30b5\u30dd\u30fc\u30c8\u3059\u308b\u5305\u62ec\u7684\u306a\u30e2\u30c7\u30eb\u5316\u304a\u3088\u3073\u56f3\u4f5c\u6210\u30d7\u30e9\u30c3\u30c8\u30d5\u30a9\u30fc\u30e0\u3067\u3059\u3002Visual Paradigm\u306f\u3001ArchiMate\u307e\u305f\u306fTOGAF\u3092\u4f7f\u7528\u3057\u3066\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u3092\u52b9\u679c\u7684\u306b\u8a2d\u8a08\u3001\u7ba1\u7406\u3001\u5171\u6709\u3059\u308b\u305f\u3081\u306e\u30c4\u30fc\u30eb\u3068\u30ea\u30bd\u30fc\u30b9\u3092\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u306b\u63d0\u4f9b\u3057\u307e\u3059\u3002<\/p>\n<p>Visual Paradigm\u3092\u4f7f\u7528\u3059\u308c\u3070\u3001\u76f4\u611f\u7684\u3067\u30c9\u30e9\u30c3\u30b0\u30a2\u30f3\u30c9\u30c9\u30ed\u30c3\u30d7\u5f0f\u306e\u30a4\u30f3\u30bf\u30fc\u30d5\u30a7\u30fc\u30b9\u3092\u4f7f\u3063\u3066ArchiMate\u56f3\u3092\u4f5c\u6210\u30fb\u7de8\u96c6\u3067\u304d\u3001\u8c4a\u5bcc\u306a\u30e2\u30c7\u30eb\u5316\u8a18\u53f7\u3068\u8868\u8a18\u6cd5\u3092\u6d3b\u7528\u3057\u3066\u3001\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u8981\u7d20\u3092\u6b63\u78ba\u306b\u8868\u73fe\u3067\u304d\u307e\u3059\u3002Visual Paradigm\u306f\u307e\u305f\u3001\u30c1\u30fc\u30e0\u30e1\u30f3\u30d0\u30fc\u3068\u7c21\u5358\u306bArchiMate\u56f3\u3092\u5171\u6709\u3057\u3001\u30ea\u30a2\u30eb\u30bf\u30a4\u30e0\u3067\u30d5\u30a3\u30fc\u30c9\u30d0\u30c3\u30af\u3084\u610f\u898b\u3092\u53ce\u96c6\u3067\u304d\u308b\u3088\u3046\u306a\u3001\u3055\u307e\u3056\u307e\u306a\u30b3\u30e9\u30dc\u30ec\u30fc\u30b7\u30e7\u30f3\u304a\u3088\u3073\u30c1\u30fc\u30e0\u30ef\u30fc\u30af\u6a5f\u80fd\u3092\u63d0\u4f9b\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/guides.visual-paradigm.com\/wp-content\/uploads\/2023\/02\/07-creating-business-process.png\"\/><\/p>\n<p>TOGAF\u3092\u6d3b\u7528\u3057\u3066\u3044\u308b\u65b9\u306e\u305f\u3081\u306b\u3001Visual Paradigm\u306fTOGAF ADM\u306e\u5b9f\u88c5\u3092\u5bb9\u6613\u306b\u3059\u308b\u5305\u62ec\u7684\u306a\u30c4\u30fc\u30eb\u3068\u30ea\u30bd\u30fc\u30b9\u306e\u30bb\u30c3\u30c8\u3092\u63d0\u4f9b\u3057\u3066\u3044\u307e\u3059\u3002Visual Paradigm\u306f\u3001\u9ad8\u30ec\u30d9\u30eb\u306e\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u4f5c\u6210\u304b\u3089\u3001\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u30b3\u30f3\u30dd\u30fc\u30cd\u30f3\u30c8\u306e\u5b9a\u7fa9\u3068\u8a2d\u8a08\u3001\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u691c\u8a3c\u304a\u3088\u3073\u5b9f\u88c5\u306e\u30e2\u30cb\u30bf\u30ea\u30f3\u30b0\u306b\u81f3\u308b\u307e\u3067\u3001TOGAF ADM\u5168\u4f53\u3092\u30b5\u30dd\u30fc\u30c8\u3057\u3066\u3044\u307e\u3059\u3002\u307e\u305f\u3001TOGAF\u306e\u6210\u679c\u7269\u3084\u30ec\u30dd\u30fc\u30c8\u3092\u4f5c\u6210\u3057\u3084\u3059\u304f\u3059\u308b\u305f\u3081\u306e\u3055\u307e\u3056\u307e\u306a\u30c4\u30fc\u30eb\u3068\u30c6\u30f3\u30d7\u30ec\u30fc\u30c8\u3082\u63d0\u4f9b\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/guides.visual-paradigm.com\/wp-content\/uploads\/2023\/02\/fill-form.png\"\/><\/p>\n<p>Visual Paradigm\u306fArchiMate\u3068TOGAF\u306e\u4e21\u65b9\u3092\u30b5\u30dd\u30fc\u30c8\u3057\u3066\u304a\u308a\u3001\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u304c\u3069\u3061\u3089\u306e\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u3092\u4f7f\u7528\u3057\u3066\u3082\u3001\u52b9\u679c\u7684\u306b\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u3092\u8a2d\u8a08\u30fb\u7ba1\u7406\u30fb\u5171\u6709\u3067\u304d\u308b\u30c4\u30fc\u30eb\u3068\u30ea\u30bd\u30fc\u30b9\u3092\u63d0\u4f9b\u3057\u307e\u3059\u3002ArchiMate\u3092\u9078\u3093\u3067\u3082\u3001TOGAF\u3092\u9078\u3093\u3067\u3082\u3001Visual Paradigm\u306f\u6210\u529f\u306b\u5fc5\u8981\u306a\u30b5\u30dd\u30fc\u30c8\u3068\u30ea\u30bd\u30fc\u30b9\u3092\u63d0\u4f9b\u3057\u307e\u3059\u3002<\/p>\n<h2>\u7d50\u8ad6<\/h2>\n<p>\u7d50\u8ad6\u3068\u3057\u3066\u3001ArchiMate\u3068TOGAF\u306f\u3069\u3061\u3089\u3082\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u305f\u3081\u306e\u5f37\u529b\u306a\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u3067\u3059\u304c\u3001\u91cd\u8981\u306a\u9055\u3044\u304c\u3042\u308a\u307e\u3059\u3002ArchiMate\u3068TOGAF\u306e\u3069\u3061\u3089\u3092\u9078\u3076\u304b\u3092\u691c\u8a0e\u3059\u308b\u969b\u306f\u3001\u3042\u306a\u305f\u306e\u7279\u5b9a\u306e\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u30cb\u30fc\u30ba\u3092\u8003\u616e\u3057\u3001\u6700\u3082\u30cb\u30fc\u30ba\u306b\u5408\u3063\u305f\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u3092\u9078\u629e\u3057\u3066\u304f\u3060\u3055\u3044\u3002ArchiMate\u3092\u9078\u3093\u3067\u3082\u3001TOGAF\u3092\u9078\u3093\u3067\u3082\u3001\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u4f5c\u696d\u3092\u652f\u3048\u308b\u9069\u5207\u306a\u30c4\u30fc\u30eb\u3068\u30ea\u30bd\u30fc\u30b9\u3092\u6301\u3063\u3066\u3044\u308b\u3053\u3068\u3092\u78ba\u8a8d\u3057\u3066\u304f\u3060\u3055\u3044\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u3068\u3057\u3066\u3001ArchiMate\u3068TOGAF\u306f\u3001\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u305f\u3081\u306e\u6700\u3082\u5e83\u304f\u4f7f\u7528\u3055\u308c\u3066\u3044\u308b\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u306e2\u3064\u3067\u3042\u308b\u53ef\u80fd\u6027\u304c\u9ad8\u3044\u3067\u3059\u3002ArchiMate\u3068TOGAF\u306e\u4e21\u65b9\u306b\u306f\u591a\u304f\u306e\u985e\u4f3c\u70b9\u304c\u3042\u308a\u307e\u3059\u304c\u3001\u91cd\u8981\u306a\u9055\u3044\u3082\u3042\u308a\u307e\u3059\u3002\u3053\u306e\u8a18\u4e8b\u3067\u306f\u3001\u3053\u308c\u3089\u306e\u9055\u3044\u3092\u691c\u8a0e\u3059\u308b\u3053\u3068\u3067\u3001\u3042\u306a\u305f\u306e\u30cb\u30fc\u30ba\u306b\u5408\u3063\u305f\u9069\u5207\u306a\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u3092\u9078\u629e\u3059\u308b\u624b\u52a9\u3051\u3092\u3057\u307e\u3059\u3002<\/p>\n","protected":false},"author":2,"featured_media":6835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"","_uag_custom_page_level_css":"","_eb_attr":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","fifu_image_url":"https:\/\/cdn-images.visual-paradigm.com\/features\/v15\/1\/archimate-tools\/archimate-diagram-example.png","fifu_image_alt":"","source_url":"","vp_image_hash":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-6834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enterprise-architecture"],"source_url":"","fifu_image_url":"https:\/\/cdn-images.visual-paradigm.com\/features\/v15\/1\/archimate-tools\/archimate-diagram-example.png","vp_image_hash":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ArchiMate\u3068TOGAF\u306e\u9055\u3044\u3092\u7406\u89e3\u3059\u308b\uff1a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u306e\u305f\u3081\u306e\u30ac\u30a4\u30c9 - Visual Paradigm Guides Japanese<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ArchiMate\u3068TOGAF\u306e\u9055\u3044\u3092\u7406\u89e3\u3059\u308b\uff1a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u306e\u305f\u3081\u306e\u30ac\u30a4\u30c9 - Visual Paradigm Guides Japanese\" \/>\n<meta property=\"og:description\" content=\"\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u3068\u3057\u3066\u3001ArchiMate\u3068TOGAF\u306f\u3001\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u305f\u3081\u306e\u6700\u3082\u5e83\u304f\u4f7f\u7528\u3055\u308c\u3066\u3044\u308b\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u306e2\u3064\u3067\u3042\u308b\u53ef\u80fd\u6027\u304c\u9ad8\u3044\u3067\u3059\u3002ArchiMate\u3068TOGAF\u306e\u4e21\u65b9\u306b\u306f\u591a\u304f\u306e\u985e\u4f3c\u70b9\u304c\u3042\u308a\u307e\u3059\u304c\u3001\u91cd\u8981\u306a\u9055\u3044\u3082\u3042\u308a\u307e\u3059\u3002\u3053\u306e\u8a18\u4e8b\u3067\u306f\u3001\u3053\u308c\u3089\u306e\u9055\u3044\u3092\u691c\u8a0e\u3059\u308b\u3053\u3068\u3067\u3001\u3042\u306a\u305f\u306e\u30cb\u30fc\u30ba\u306b\u5408\u3063\u305f\u9069\u5207\u306a\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u3092\u9078\u629e\u3059\u308b\u624b\u52a9\u3051\u3092\u3057\u307e\u3059\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/\" \/>\n<meta property=\"og:site_name\" content=\"Visual Paradigm Guides Japanese\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-05T18:25:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn-images.visual-paradigm.com\/features\/v15\/1\/archimate-tools\/archimate-diagram-example.png\" \/><meta property=\"og:image\" content=\"https:\/\/cdn-images.visual-paradigm.com\/features\/v15\/1\/archimate-tools\/archimate-diagram-example.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"658\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cdn-images.visual-paradigm.com\/features\/v15\/1\/archimate-tools\/archimate-diagram-example.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"vpjick\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/\"},\"headline\":\"ArchiMate\u3068TOGAF\u306e\u9055\u3044\u3092\u7406\u89e3\u3059\u308b\uff1a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u306e\u305f\u3081\u306e\u30ac\u30a4\u30c9\",\"datePublished\":\"2026-02-05T18:25:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/\"},\"wordCount\":76,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example.png\",\"articleSection\":[\"Enterprise Architecture\"],\"inLanguage\":\"ja\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/\",\"url\":\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/\",\"name\":\"ArchiMate\u3068TOGAF\u306e\u9055\u3044\u3092\u7406\u89e3\u3059\u308b\uff1a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u306e\u305f\u3081\u306e\u30ac\u30a4\u30c9 - Visual Paradigm Guides Japanese\",\"isPartOf\":{\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example.png\",\"datePublished\":\"2026-02-05T18:25:53+00:00\",\"author\":{\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/#\/schema\/person\/0903402359ce4a6eeeaa70bb7204a2c6\"},\"breadcrumb\":{\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#primaryimage\",\"url\":\"https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example.png\",\"contentUrl\":\"https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example.png\",\"width\":1170,\"height\":658},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/guides.visual-paradigm.com\/ja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enterprise Architecture\",\"item\":\"https:\/\/guides.visual-paradigm.com\/ja\/category\/enterprise-architecture\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ArchiMate\u3068TOGAF\u306e\u9055\u3044\u3092\u7406\u89e3\u3059\u308b\uff1a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u306e\u305f\u3081\u306e\u30ac\u30a4\u30c9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/guides.visual-paradigm.com\/ja\/#website\",\"url\":\"https:\/\/guides.visual-paradigm.com\/ja\/\",\"name\":\"Visual Paradigm Guides Japanese\",\"description\":\"Smart guides for an AI-driven world\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/guides.visual-paradigm.com\/ja\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ArchiMate\u3068TOGAF\u306e\u9055\u3044\u3092\u7406\u89e3\u3059\u308b\uff1a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u306e\u305f\u3081\u306e\u30ac\u30a4\u30c9 - Visual Paradigm Guides Japanese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/","og_locale":"ja_JP","og_type":"article","og_title":"ArchiMate\u3068TOGAF\u306e\u9055\u3044\u3092\u7406\u89e3\u3059\u308b\uff1a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u306e\u305f\u3081\u306e\u30ac\u30a4\u30c9 - Visual Paradigm Guides Japanese","og_description":"\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u3068\u3057\u3066\u3001ArchiMate\u3068TOGAF\u306f\u3001\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u305f\u3081\u306e\u6700\u3082\u5e83\u304f\u4f7f\u7528\u3055\u308c\u3066\u3044\u308b\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u306e2\u3064\u3067\u3042\u308b\u53ef\u80fd\u6027\u304c\u9ad8\u3044\u3067\u3059\u3002ArchiMate\u3068TOGAF\u306e\u4e21\u65b9\u306b\u306f\u591a\u304f\u306e\u985e\u4f3c\u70b9\u304c\u3042\u308a\u307e\u3059\u304c\u3001\u91cd\u8981\u306a\u9055\u3044\u3082\u3042\u308a\u307e\u3059\u3002\u3053\u306e\u8a18\u4e8b\u3067\u306f\u3001\u3053\u308c\u3089\u306e\u9055\u3044\u3092\u691c\u8a0e\u3059\u308b\u3053\u3068\u3067\u3001\u3042\u306a\u305f\u306e\u30cb\u30fc\u30ba\u306b\u5408\u3063\u305f\u9069\u5207\u306a\u30e2\u30c7\u30eb\u5316\u8a00\u8a9e\u3092\u9078\u629e\u3059\u308b\u624b\u52a9\u3051\u3092\u3057\u307e\u3059\u3002","og_url":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/","og_site_name":"Visual Paradigm Guides Japanese","article_published_time":"2026-02-05T18:25:53+00:00","og_image":[{"url":"https:\/\/cdn-images.visual-paradigm.com\/features\/v15\/1\/archimate-tools\/archimate-diagram-example.png","type":"","width":"","height":""},{"width":1170,"height":658,"url":"https:\/\/cdn-images.visual-paradigm.com\/features\/v15\/1\/archimate-tools\/archimate-diagram-example.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cdn-images.visual-paradigm.com\/features\/v15\/1\/archimate-tools\/archimate-diagram-example.png","twitter_misc":{"\u57f7\u7b46\u8005":"vpjick","\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"4\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#article","isPartOf":{"@id":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/"},"headline":"ArchiMate\u3068TOGAF\u306e\u9055\u3044\u3092\u7406\u89e3\u3059\u308b\uff1a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u306e\u305f\u3081\u306e\u30ac\u30a4\u30c9","datePublished":"2026-02-05T18:25:53+00:00","mainEntityOfPage":{"@id":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/"},"wordCount":76,"commentCount":0,"image":{"@id":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#primaryimage"},"thumbnailUrl":"https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example.png","articleSection":["Enterprise Architecture"],"inLanguage":"ja"},{"@type":"WebPage","@id":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/","url":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/","name":"ArchiMate\u3068TOGAF\u306e\u9055\u3044\u3092\u7406\u89e3\u3059\u308b\uff1a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u306e\u305f\u3081\u306e\u30ac\u30a4\u30c9 - Visual Paradigm Guides Japanese","isPartOf":{"@id":"https:\/\/guides.visual-paradigm.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#primaryimage"},"image":{"@id":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#primaryimage"},"thumbnailUrl":"https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example.png","datePublished":"2026-02-05T18:25:53+00:00","author":{"@id":"https:\/\/guides.visual-paradigm.com\/ja\/#\/schema\/person\/0903402359ce4a6eeeaa70bb7204a2c6"},"breadcrumb":{"@id":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#primaryimage","url":"https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example.png","contentUrl":"https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example.png","width":1170,"height":658},{"@type":"BreadcrumbList","@id":"https:\/\/guides.visual-paradigm.com\/ja\/understanding-the-differences-between-archimate-and-togaf-a-guide-for-enterprise-architects\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/guides.visual-paradigm.com\/ja\/"},{"@type":"ListItem","position":2,"name":"Enterprise Architecture","item":"https:\/\/guides.visual-paradigm.com\/ja\/category\/enterprise-architecture\/"},{"@type":"ListItem","position":3,"name":"ArchiMate\u3068TOGAF\u306e\u9055\u3044\u3092\u7406\u89e3\u3059\u308b\uff1a\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u306e\u305f\u3081\u306e\u30ac\u30a4\u30c9"}]},{"@type":"WebSite","@id":"https:\/\/guides.visual-paradigm.com\/ja\/#website","url":"https:\/\/guides.visual-paradigm.com\/ja\/","name":"Visual Paradigm Guides Japanese","description":"Smart guides for an AI-driven world","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guides.visual-paradigm.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"}]}},"uagb_featured_image_src":{"full":["https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example.png",1170,658,false],"thumbnail":["https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example-150x150.png",150,150,true],"medium":["https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example-300x169.png",300,169,true],"medium_large":["https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example-768x432.png",768,432,true],"large":["https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example-1024x576.png",1024,576,true],"1536x1536":["https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example.png",1170,658,false],"2048x2048":["https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example.png",1170,658,false],"neve-blog":["https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example-930x620.png",930,620,true],"yarpp-thumbnail":["https:\/\/guides.visual-paradigm.com\/ja\/wp-content\/uploads\/sites\/4\/2026\/02\/archimate-diagram-example.png",120,67,false]},"uagb_author_info":{"display_name":"vpjick","author_link":"https:\/\/guides.visual-paradigm.com\/ja\/author\/vpjick\/"},"uagb_comment_info":0,"uagb_excerpt":"\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c8\u3068\u3057\u3066\u3001ArchiMate\u3068TOGAF\u306f\u3001\u30a8\u30f3\u30bf\u30fc\u30d7\u30e9\u30a4\u30ba\u30a2\u30fc\u30ad\u30c6\u30af\u30c1\u30e3\u306e\u305f\u3081\u306e\u6700&hellip;","_links":{"self":[{"href":"https:\/\/guides.visual-paradigm.com\/ja\/wp-json\/wp\/v2\/posts\/6834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guides.visual-paradigm.com\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guides.visual-paradigm.com\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guides.visual-paradigm.com\/ja\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guides.visual-paradigm.com\/ja\/wp-json\/wp\/v2\/comments?post=6834"}],"version-history":[{"count":0,"href":"https:\/\/guides.visual-paradigm.com\/ja\/wp-json\/wp\/v2\/posts\/6834\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guides.visual-paradigm.com\/ja\/wp-json\/wp\/v2\/media\/6835"}],"wp:attachment":[{"href":"https:\/\/guides.visual-paradigm.com\/ja\/wp-json\/wp\/v2\/media?parent=6834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guides.visual-paradigm.com\/ja\/wp-json\/wp\/v2\/categories?post=6834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guides.visual-paradigm.com\/ja\/wp-json\/wp\/v2\/tags?post=6834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}